{"id":9113,"date":"2024-08-29T15:23:30","date_gmt":"2024-08-29T19:23:30","guid":{"rendered":"https:\/\/reseaudialogue.ca\/?p=9113"},"modified":"2025-03-26T13:45:14","modified_gmt":"2025-03-26T17:45:14","slug":"nouveau-ca-2024","status":"publish","type":"post","link":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee","title":{"rendered":"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9113\" class=\"elementor elementor-9113\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51db4404 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51db4404\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4edf035f\" data-id=\"4edf035f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea2936a elementor-widget elementor-widget-text-editor\" data-id=\"ea2936a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"940\" height=\"788\" class=\"wp-image-9116\" src=\"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png\" alt=\"\" srcset=\"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png 940w, https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5-600x503.png 600w, https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5-768x644.png 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\"><strong>Ottawa, le 29 ao\u00fbt 2024<\/strong> \u2013 suite \u00e0 la tenue de son Assembl\u00e9e g\u00e9n\u00e9rale annuelle, le 27\u00a0ao\u00fbt dernier, la Fondation dialogue est heureuse de vous pr\u00e9senter la nouvelle composition de son conseil d\u2019administration pour l\u2019ann\u00e9e 2024-2025.<\/p>\n\n<p class=\"wp-block-paragraph\">La Fondation dialogue accueille trois nouveaux membres du conseil d\u2019administration, soit :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Marie-Claude Rioux<\/strong>, <em>Vice-pr\u00e9sidence<\/em>\u2014 gestionnaire avec plus de 25 ans d&rsquo;exp\u00e9rience dans le secteur des OBNL, est directrice g\u00e9n\u00e9rale du COPA National et une conf\u00e9renci\u00e8re reconnue, active dans la communaut\u00e9 et sp\u00e9cialis\u00e9e dans les droits linguistiques et la culture acadienne \u00e0 Dartmouth, Nouvelle-\u00c9cosse.<\/li>\n\n<li><strong>Ang\u00e9lique Bernard<\/strong>, <em>Administrator<\/em>\u2014 traductrice et r\u00e9viseure bilingue, est l&rsquo;ancienne commissaire du Yukon et dirige d\u00e9sormais une entreprise de services de traduction et de coordination de projets \u00e0 Whitehorse, au Yukon.<\/li>\n\n<li><strong>Genevi\u00e8ve Pelletier<\/strong>, <em>Administrator<\/em>\u2014 cr\u00e9atrice et metteuse en sc\u00e8ne m\u00e9tisse, est directrice artistique du Th\u00e9\u00e2tre Cercle Moli\u00e8re depuis 2012 et s&rsquo;int\u00e9resse aux croisements culturels pour enrichir la cr\u00e9ation artistique \u00e0 Winnipeg, Manitoba.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Par ailleurs, la Fondation dialogue tient \u00e0 exprimer sa reconnaissance envers les membres sortants du Conseil d\u2019administration pour leur contribution inestimable. Un immense merci \u00e0 Allister Surette, Fran\u00e7oise Enguehard, Daphn\u00e9 Kathia Rosalbert et Paulette Duguay pour leurs contributions remarquables et leur d\u00e9vouement exceptionnel.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c9galement, lors de cette Assembl\u00e9e g\u00e9n\u00e9rale annuelle, la direction g\u00e9n\u00e9rale de la Fondation dialogue Aj\u00e0 Besler a fi\u00e8rement pr\u00e9sent\u00e9 le <a href=\"http:\/\/reseaudialogue.ca\/wp-content\/uploads\/EnglishV_RA2023.pdf\">Annual Report 2023-2024<\/a>, qui repr\u00e9sente le travail infatigable\u00a0d\u2019une \u00e9quipe dynamique\u00a0et engag\u00e9e.\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019ensemble du conseil d\u2019administration 2024-2025 de la Fondation dialogue :<\/strong><\/p>\n\n<figure class=\"wp-block-table\">\n<table class=\"has-fixed-layout\">\n<tbody>\n<tr>\n<td><strong>Nom<\/strong><\/td>\n<td><strong>Poste<\/strong><\/td>\n<td><strong>R\u00e9gion<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Chedly Belkhodja<\/strong><\/td>\n<td>Pr\u00e9sidence<\/td>\n<td>Qu\u00e9bec<\/td>\n<\/tr>\n<tr>\n<td><strong>Marie-Claude Rioux<\/strong><\/td>\n<td>Vice-pr\u00e9sidence<\/td>\n<td>Nova Scotia<\/td>\n<\/tr>\n<tr>\n<td><strong>Suzanne Jacob<\/strong><\/td>\n<td>Treasurer<\/td>\n<td>British Columbia<\/td>\n<\/tr>\n<tr>\n<td><strong>Fran\u00e7oise Sigur-Cloutier<\/strong><\/td>\n<td>Secretary<\/td>\n<td>Alberta<\/td>\n<\/tr>\n<tr>\n<td><strong>Ang\u00e9lique Bernard<\/strong><\/td>\n<td>Administrator<\/td>\n<td>Yukon<\/td>\n<\/tr>\n<tr>\n<td><strong>Pierre Jury<\/strong><\/td>\n<td>Administrateur<\/td>\n<td>Ontario<\/td>\n<\/tr>\n<tr>\n<td><strong>Genevi\u00e8ve Pelletier<\/strong><\/td>\n<td>Administrator<\/td>\n<td>Manitoba<\/td>\n<\/tr>\n<tr>\n<td><strong>Liane Roy<\/strong><\/td>\n<td>Pr\u00e9sidence de la FCFA<\/td>\n<td>New Brunswick<\/td>\n<\/tr>\n<tr>\n<td><strong>Yvon Godin<\/strong><\/td>\n<td>Administrateur<\/td>\n<td>New Brunswick<\/td>\n<\/tr>\n<tr>\n<td><strong>Claire Thibideau<\/strong><\/td>\n<td>Administrator<\/td>\n<td>Ontario<\/td>\n<\/tr>\n<tr>\n<td><strong>Paula Popescu<\/strong><\/td>\n<td>Administrator<\/td>\n<td>Qu\u00e9bec<\/td>\n<\/tr>\n<tr>\n<td><strong>Ania Kolodziej<\/strong><\/td>\n<td>Administrator<\/td>\n<td>British Columbia<\/td>\n<\/tr>\n<tr>\n<td><strong>Jenny Matingu<\/strong><\/td>\n<td>Administrator<\/td>\n<td>Ontario<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/reseaudialogue.ca\/en\/equipe-conseil-dadministration\/\"><strong>En savoir plus sur les membres du conseil d\u2019administration<\/strong><\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 PROPOS DE LA FONDATION DIALOGUE<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Fond\u00e9e en 2004, la Fondation dialogue est un organisme de bienfaisance qui a pour mission, dans un esprit de collaboration, d\u2019engager un dialogue durable au sein de la francophonie et avec toute la diversit\u00e9 du Canada.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ottawa, le 29 ao\u00fbt 2024 \u2013 suite \u00e0 la tenue de son Assembl\u00e9e g\u00e9n\u00e9rale annuelle, le 27\u00a0ao\u00fbt dernier, la Fondation dialogue est heureuse de vous pr\u00e9senter la nouvelle composition de son conseil d\u2019administration pour l\u2019ann\u00e9e 2024-2025. La Fondation dialogue accueille trois nouveaux membres du conseil d\u2019administration, soit : Par ailleurs, la Fondation dialogue tient \u00e0 [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":9116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fondation dialogue accueille des nouveaux membres \u00e0 son CA &#8212; R\u00e9seau dialogue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA &#8212; R\u00e9seau dialogue\" \/>\n<meta property=\"og:description\" content=\"Ottawa, le 29 ao\u00fbt 2024 \u2013 suite \u00e0 la tenue de son Assembl\u00e9e g\u00e9n\u00e9rale annuelle, le 27\u00a0ao\u00fbt dernier, la Fondation dialogue est heureuse de vous pr\u00e9senter la nouvelle composition de son conseil d\u2019administration pour l\u2019ann\u00e9e 2024-2025. La Fondation dialogue accueille trois nouveaux membres du conseil d\u2019administration, soit : Par ailleurs, la Fondation dialogue tient \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau dialogue\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T19:23:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T17:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lelia Farhat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lelia Farhat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee\"},\"author\":{\"name\":\"Lelia Farhat\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#\\\/schema\\\/person\\\/b066a312bc46999e4e18bfb28ecfbac7\"},\"headline\":\"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA\",\"datePublished\":\"2024-08-29T19:23:30+00:00\",\"dateModified\":\"2025-03-26T17:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reseaudialogue.ca\\\/wp-content\\\/uploads\\\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee\",\"url\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee\",\"name\":\"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA &#8212; R\u00e9seau dialogue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reseaudialogue.ca\\\/wp-content\\\/uploads\\\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png\",\"datePublished\":\"2024-08-29T19:23:30+00:00\",\"dateModified\":\"2025-03-26T17:45:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#primaryimage\",\"url\":\"https:\\\/\\\/reseaudialogue.ca\\\/wp-content\\\/uploads\\\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png\",\"contentUrl\":\"https:\\\/\\\/reseaudialogue.ca\\\/wp-content\\\/uploads\\\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/nouveau-ca-2024\\\/non-classifiee#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/reseaudialogue.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#website\",\"url\":\"https:\\\/\\\/reseaudialogue.ca\\\/\",\"name\":\"R\u00e9seau dialogue\",\"description\":\"R\u00e9seau dialogue\",\"publisher\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reseaudialogue.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#organization\",\"name\":\"R\u00e9seau dialogue\",\"url\":\"https:\\\/\\\/reseaudialogue.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/reseaudialogue.ca\\\/wp-content\\\/uploads\\\/1dialogue-logo-full-color-cmyk.png\",\"contentUrl\":\"https:\\\/\\\/reseaudialogue.ca\\\/wp-content\\\/uploads\\\/1dialogue-logo-full-color-cmyk.png\",\"width\":707,\"height\":249,\"caption\":\"R\u00e9seau dialogue\"},\"image\":{\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/reseaudialogue.ca\\\/#\\\/schema\\\/person\\\/b066a312bc46999e4e18bfb28ecfbac7\",\"name\":\"Lelia Farhat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/700a4d6b709745579c23e82fffd023876188414de6d9a859634be0e00df1ec65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/700a4d6b709745579c23e82fffd023876188414de6d9a859634be0e00df1ec65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/700a4d6b709745579c23e82fffd023876188414de6d9a859634be0e00df1ec65?s=96&d=mm&r=g\",\"caption\":\"Lelia Farhat\"},\"url\":\"https:\\\/\\\/reseaudialogue.ca\\\/en\\\/author\\\/l-farhatreseaudialogue-ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA &#8212; R\u00e9seau dialogue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee","og_locale":"en_US","og_type":"article","og_title":"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA &#8212; R\u00e9seau dialogue","og_description":"Ottawa, le 29 ao\u00fbt 2024 \u2013 suite \u00e0 la tenue de son Assembl\u00e9e g\u00e9n\u00e9rale annuelle, le 27\u00a0ao\u00fbt dernier, la Fondation dialogue est heureuse de vous pr\u00e9senter la nouvelle composition de son conseil d\u2019administration pour l\u2019ann\u00e9e 2024-2025. La Fondation dialogue accueille trois nouveaux membres du conseil d\u2019administration, soit : Par ailleurs, la Fondation dialogue tient \u00e0 [&hellip;]","og_url":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee","og_site_name":"R\u00e9seau dialogue","article_published_time":"2024-08-29T19:23:30+00:00","article_modified_time":"2025-03-26T17:45:14+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png","type":"image\/png"}],"author":"Lelia Farhat","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lelia Farhat","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#article","isPartOf":{"@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee"},"author":{"name":"Lelia Farhat","@id":"https:\/\/reseaudialogue.ca\/#\/schema\/person\/b066a312bc46999e4e18bfb28ecfbac7"},"headline":"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA","datePublished":"2024-08-29T19:23:30+00:00","dateModified":"2025-03-26T17:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee"},"wordCount":404,"publisher":{"@id":"https:\/\/reseaudialogue.ca\/#organization"},"image":{"@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#primaryimage"},"thumbnailUrl":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-CA"},{"@type":"WebPage","@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee","url":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee","name":"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA &#8212; R\u00e9seau dialogue","isPartOf":{"@id":"https:\/\/reseaudialogue.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#primaryimage"},"image":{"@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#primaryimage"},"thumbnailUrl":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png","datePublished":"2024-08-29T19:23:30+00:00","dateModified":"2025-03-26T17:45:14+00:00","breadcrumb":{"@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#primaryimage","url":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png","contentUrl":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/Gray-Black-Minimalist-Fashion-New-Arrival-Promotion-Banner-5.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/reseaudialogue.ca\/en\/nouveau-ca-2024\/non-classifiee#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reseaudialogue.ca\/"},{"@type":"ListItem","position":2,"name":"La Fondation dialogue accueille des nouveaux membres \u00e0 son CA"}]},{"@type":"WebSite","@id":"https:\/\/reseaudialogue.ca\/#website","url":"https:\/\/reseaudialogue.ca\/","name":"Dialogue Network","description":"Dialogue Network","publisher":{"@id":"https:\/\/reseaudialogue.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reseaudialogue.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/reseaudialogue.ca\/#organization","name":"Dialogue Network","url":"https:\/\/reseaudialogue.ca\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/reseaudialogue.ca\/#\/schema\/logo\/image\/","url":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/1dialogue-logo-full-color-cmyk.png","contentUrl":"https:\/\/reseaudialogue.ca\/wp-content\/uploads\/1dialogue-logo-full-color-cmyk.png","width":707,"height":249,"caption":"R\u00e9seau dialogue"},"image":{"@id":"https:\/\/reseaudialogue.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/reseaudialogue.ca\/#\/schema\/person\/b066a312bc46999e4e18bfb28ecfbac7","name":"Lelia Farhat","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/700a4d6b709745579c23e82fffd023876188414de6d9a859634be0e00df1ec65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/700a4d6b709745579c23e82fffd023876188414de6d9a859634be0e00df1ec65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/700a4d6b709745579c23e82fffd023876188414de6d9a859634be0e00df1ec65?s=96&d=mm&r=g","caption":"Lelia Farhat"},"url":"https:\/\/reseaudialogue.ca\/en\/author\/l-farhatreseaudialogue-ca"}]}},"_links":{"self":[{"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/posts\/9113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/comments?post=9113"}],"version-history":[{"count":5,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/posts\/9113\/revisions"}],"predecessor-version":[{"id":9676,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/posts\/9113\/revisions\/9676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/media\/9116"}],"wp:attachment":[{"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/media?parent=9113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/categories?post=9113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reseaudialogue.ca\/en\/wp-json\/wp\/v2\/tags?post=9113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}